{"id":379,"date":"2011-09-19T16:15:00","date_gmt":"2011-09-19T14:15:00","guid":{"rendered":"https:\/\/www.princess.ch\/blog\/2011\/09\/mit-den-geburtstagsgeschenken-ist-es-immer-so-eine\/"},"modified":"2014-02-20T16:47:41","modified_gmt":"2014-02-20T15:47:41","slug":"perlenkuche-geschenketip","status":"publish","type":"post","link":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/","title":{"rendered":"Geschenketipp: Perlenk\u00fcche"},"content":{"rendered":"<div class=\"mceTemp\">\n<dl>\n<dt><img decoding=\"async\" src=\"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2012\/03\/tumblr_lrrwyf4Ybo1qgsy98o1_1280-1024x768.jpg\"  alt=\"Geschenketipp: Perlenk\u00fcche\"  width=\"620\" height=\"465\" \/><\/dt>\n<dt><\/dt>\n<\/dl>\n<div>\n<p>Mit den Geburtstagsgeschenken ist es immer so eine Sache. Geschenke, die keinen pers\u00f6nlichen Bezug haben, machen f\u00fcr mich keinen Sinn!<\/p>\n<p>Dank <a href=\"http:\/\/twitter.com\/#%21\/theswiss\" target=\"_blank\">@theswiss<\/a> habe ich mich wieder an die <a href=\"http:\/\/www.perlenkueche.ch\/\" target=\"_blank\">Perlenk\u00fcche<\/a> erinnert. Eine wirklich tolle Umsetzung von s\u00fcssen Kleinigkeiten als Schmuck oder auch in Form von Magneten.<\/p>\n<p>Schlussendlich bekam eine gute Freundin einen Back-Gutschein inklusive zweier kleiner Magnete in From von einem Zimstern und einer Schwedentorte.<\/p>\n<p>Vielen Dank an Perlenk\u00f6chin <a href=\"http:\/\/twitter.com\/#%21\/fvongruenigen\" target=\"_blank\">@fvongruenigen<\/a> f\u00fcr die spontane Umsetzungung meiner Bestellung!<\/p>\n<\/div>\n<dl id=\"attachment_380\">\n<dt><\/dt>\n<\/dl>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit den Geburtstagsgeschenken ist es immer so eine Sache. Geschenke, die keinen pers\u00f6nlichen Bezug haben, machen f\u00fcr mich keinen Sinn! Dank @theswiss habe ich mich wieder an die Perlenk\u00fcche erinnert. Eine wirklich tolle Umsetzung von s\u00fcssen Kleinigkeiten als Schmuck oder auch in Form von Magneten. Schlussendlich bekam eine gute Freundin einen Back-Gutschein inklusive zweier kleiner<\/p>\n","protected":false},"author":8,"featured_media":380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[417],"tags":[653,658,668],"class_list":["post-379","post","type-post","status-publish","format-standard","has-post-thumbnail","category-shopping","tag-onlineshop","tag-schmuck","tag-selbstgemacht"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geschenketipp: Perlenk\u00fcche - Food- &amp; Reiseblog - Princess.ch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geschenketipp: Perlenk\u00fcche - Food- &amp; Reiseblog - Princess.ch\" \/>\n<meta property=\"og:description\" content=\"Mit den Geburtstagsgeschenken ist es immer so eine Sache. Geschenke, die keinen pers\u00f6nlichen Bezug haben, machen f\u00fcr mich keinen Sinn! Dank @theswiss habe ich mich wieder an die Perlenk\u00fcche erinnert. Eine wirklich tolle Umsetzung von s\u00fcssen Kleinigkeiten als Schmuck oder auch in Form von Magneten. Schlussendlich bekam eine gute Freundin einen Back-Gutschein inklusive zweier kleiner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/\" \/>\n<meta property=\"og:site_name\" content=\"Reiseblog &amp; Food-Blog aus der Schweiz - princess.ch\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/princess.schweiz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/princess.schweiz\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-19T14:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-20T15:47:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2012\/03\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/princessCH\" \/>\n<meta name=\"twitter:site\" content=\"@princessCH\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/\"},\"author\":{\"name\":\"Nicole\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#\\\/schema\\\/person\\\/6d3b8cbe934cec887d0a6ec1d263daad\"},\"headline\":\"Geschenketipp: Perlenk\u00fcche\",\"datePublished\":\"2011-09-19T14:15:00+00:00\",\"dateModified\":\"2014-02-20T15:47:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/\"},\"wordCount\":84,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg\",\"keywords\":[\"Onlineshop\",\"Schmuck\",\"Selbstgemacht\"],\"articleSection\":[\"Shopping Tipps\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/\",\"url\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/\",\"name\":\"Geschenketipp: Perlenk\u00fcche - Food- & Reiseblog - Princess.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg\",\"datePublished\":\"2011-09-19T14:15:00+00:00\",\"dateModified\":\"2014-02-20T15:47:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg\",\"width\":\"1280\",\"height\":\"960\",\"caption\":\"Mit den Geburtstagsgeschenken ist es immer so eine Sache. Geschenke, die keinen pers\u00f6nlichen Bezug h\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/perlenkuche-geschenketip\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shopping Tipps\",\"item\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/shopping\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Geschenketipp: Perlenk\u00fcche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/\",\"name\":\"Reiseblog &amp; Food-Blog aus der Schweiz - princess.ch\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#organization\",\"name\":\"princess.ch\",\"url\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Blog_logo_PRINCESS_v3.png\",\"contentUrl\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Blog_logo_PRINCESS_v3.png\",\"width\":526,\"height\":250,\"caption\":\"princess.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/princess.schweiz\",\"https:\\\/\\\/x.com\\\/princessCH\",\"https:\\\/\\\/www.instagram.com\\\/princess_ch\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/princessch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/PrincessCh\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/#\\\/schema\\\/person\\\/6d3b8cbe934cec887d0a6ec1d263daad\",\"name\":\"Nicole\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/b28a29bc03df3d23a79179e4451b2f63.jpg?ver=1783787403\",\"url\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/b28a29bc03df3d23a79179e4451b2f63.jpg?ver=1783787403\",\"contentUrl\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/b28a29bc03df3d23a79179e4451b2f63.jpg?ver=1783787403\",\"caption\":\"Nicole\"},\"description\":\"Sie berichtet \u00fcber alles was Frauen interessiert &amp; mag graue Haare, vor allem wenn sie an Robbie Williams sind &lt;3. Eine weitere Schw\u00e4che hat sie f\u00fcr die s\u00fcssen S\u00fcnden dieser Welt &amp; ist ein richtiger Foodie.\",\"sameAs\":[\"https:\\\/\\\/www.princess.ch\",\"https:\\\/\\\/www.facebook.com\\\/princess.schweiz\\\/\",\"https:\\\/\\\/instagram.com\\\/princess_ch\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nicolenobs\\\/\",\"https:\\\/\\\/pinterest.com\\\/princessch\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/princessCH\",\"https:\\\/\\\/youtube.com\\\/c\\\/PrincessCh\"],\"url\":\"https:\\\/\\\/www.princess.ch\\\/blog\\\/author\\\/nicole8213\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geschenketipp: Perlenk\u00fcche - Food- & Reiseblog - Princess.ch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/","og_locale":"de_DE","og_type":"article","og_title":"Geschenketipp: Perlenk\u00fcche - Food- & Reiseblog - Princess.ch","og_description":"Mit den Geburtstagsgeschenken ist es immer so eine Sache. Geschenke, die keinen pers\u00f6nlichen Bezug haben, machen f\u00fcr mich keinen Sinn! Dank @theswiss habe ich mich wieder an die Perlenk\u00fcche erinnert. Eine wirklich tolle Umsetzung von s\u00fcssen Kleinigkeiten als Schmuck oder auch in Form von Magneten. Schlussendlich bekam eine gute Freundin einen Back-Gutschein inklusive zweier kleiner","og_url":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/","og_site_name":"Reiseblog &amp; Food-Blog aus der Schweiz - princess.ch","article_publisher":"http:\/\/facebook.com\/princess.schweiz","article_author":"https:\/\/www.facebook.com\/princess.schweiz\/","article_published_time":"2011-09-19T14:15:00+00:00","article_modified_time":"2014-02-20T15:47:41+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2012\/03\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg","type":"image\/jpeg"}],"author":"Nicole","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/princessCH","twitter_site":"@princessCH","twitter_misc":{"Verfasst von":"Nicole"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/#article","isPartOf":{"@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/"},"author":{"name":"Nicole","@id":"https:\/\/www.princess.ch\/blog\/#\/schema\/person\/6d3b8cbe934cec887d0a6ec1d263daad"},"headline":"Geschenketipp: Perlenk\u00fcche","datePublished":"2011-09-19T14:15:00+00:00","dateModified":"2014-02-20T15:47:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/"},"wordCount":84,"commentCount":0,"publisher":{"@id":"https:\/\/www.princess.ch\/blog\/#organization"},"image":{"@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/#primaryimage"},"thumbnailUrl":"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2012\/03\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg","keywords":["Onlineshop","Schmuck","Selbstgemacht"],"articleSection":["Shopping Tipps"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/","url":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/","name":"Geschenketipp: Perlenk\u00fcche - Food- & Reiseblog - Princess.ch","isPartOf":{"@id":"https:\/\/www.princess.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/#primaryimage"},"image":{"@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/#primaryimage"},"thumbnailUrl":"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2012\/03\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg","datePublished":"2011-09-19T14:15:00+00:00","dateModified":"2014-02-20T15:47:41+00:00","breadcrumb":{"@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/#primaryimage","url":"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2012\/03\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg","contentUrl":"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2012\/03\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg","width":"1280","height":"960","caption":"Mit den Geburtstagsgeschenken ist es immer so eine Sache. Geschenke, die keinen pers\u00f6nlichen Bezug h"},{"@type":"BreadcrumbList","@id":"https:\/\/www.princess.ch\/blog\/perlenkuche-geschenketip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.princess.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Shopping Tipps","item":"https:\/\/www.princess.ch\/blog\/shopping\/"},{"@type":"ListItem","position":3,"name":"Geschenketipp: Perlenk\u00fcche"}]},{"@type":"WebSite","@id":"https:\/\/www.princess.ch\/blog\/#website","url":"https:\/\/www.princess.ch\/blog\/","name":"Reiseblog &amp; Food-Blog aus der Schweiz - princess.ch","description":"","publisher":{"@id":"https:\/\/www.princess.ch\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.princess.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.princess.ch\/blog\/#organization","name":"princess.ch","url":"https:\/\/www.princess.ch\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.princess.ch\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2017\/03\/Blog_logo_PRINCESS_v3.png","contentUrl":"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2017\/03\/Blog_logo_PRINCESS_v3.png","width":526,"height":250,"caption":"princess.ch"},"image":{"@id":"https:\/\/www.princess.ch\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/princess.schweiz","https:\/\/x.com\/princessCH","https:\/\/www.instagram.com\/princess_ch\/","https:\/\/www.pinterest.com\/princessch\/","https:\/\/www.youtube.com\/c\/PrincessCh"]},{"@type":"Person","@id":"https:\/\/www.princess.ch\/blog\/#\/schema\/person\/6d3b8cbe934cec887d0a6ec1d263daad","name":"Nicole","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.princess.ch\/blog\/wp-content\/litespeed\/avatar\/b28a29bc03df3d23a79179e4451b2f63.jpg?ver=1783787403","url":"https:\/\/www.princess.ch\/blog\/wp-content\/litespeed\/avatar\/b28a29bc03df3d23a79179e4451b2f63.jpg?ver=1783787403","contentUrl":"https:\/\/www.princess.ch\/blog\/wp-content\/litespeed\/avatar\/b28a29bc03df3d23a79179e4451b2f63.jpg?ver=1783787403","caption":"Nicole"},"description":"Sie berichtet \u00fcber alles was Frauen interessiert &amp; mag graue Haare, vor allem wenn sie an Robbie Williams sind &lt;3. Eine weitere Schw\u00e4che hat sie f\u00fcr die s\u00fcssen S\u00fcnden dieser Welt &amp; ist ein richtiger Foodie.","sameAs":["https:\/\/www.princess.ch","https:\/\/www.facebook.com\/princess.schweiz\/","https:\/\/instagram.com\/princess_ch","https:\/\/www.linkedin.com\/in\/nicolenobs\/","https:\/\/pinterest.com\/princessch","https:\/\/x.com\/https:\/\/twitter.com\/princessCH","https:\/\/youtube.com\/c\/PrincessCh"],"url":"https:\/\/www.princess.ch\/blog\/author\/nicole8213\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.princess.ch\/blog\/wp-content\/uploads\/2012\/03\/tumblr_lrrwyf4Ybo1qgsy98o1_1280.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2Cb1a-67","_links":{"self":[{"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/posts\/379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/comments?post=379"}],"version-history":[{"count":0,"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/posts\/379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/media\/380"}],"wp:attachment":[{"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/media?parent=379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/categories?post=379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.princess.ch\/blog\/wp-json\/wp\/v2\/tags?post=379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}